{"id":600,"count":1,"description":"","link":"https:\/\/rabsportsnews.com\/de\/tag\/moses-waiswa\/","name":"Moses Waiswa","slug":"moses-waiswa","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moses Waiswa Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rabsportsnews.com\/de\/tag\/moses-waiswa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moses Waiswa Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rabsportsnews.com\/de\/tag\/moses-waiswa\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@rabsportsnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rabsportsnews.com\\\/tag\\\/moses-waiswa\\\/\",\"url\":\"https:\\\/\\\/rabsportsnews.com\\\/tag\\\/moses-waiswa\\\/\",\"name\":\"Moses Waiswa Archives -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rabsportsnews.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rabsportsnews.com\\\/tag\\\/moses-waiswa\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rabsportsnews.com\\\/tag\\\/moses-waiswa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rabsportsnews.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moses Waiswa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rabsportsnews.com\\\/#website\",\"url\":\"https:\\\/\\\/rabsportsnews.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rabsportsnews.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moses Waiswa Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rabsportsnews.com\/de\/tag\/moses-waiswa\/","og_locale":"de_DE","og_type":"article","og_title":"Moses Waiswa Archives -","og_url":"https:\/\/rabsportsnews.com\/de\/tag\/moses-waiswa\/","twitter_card":"summary_large_image","twitter_site":"@rabsportsnews","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rabsportsnews.com\/tag\/moses-waiswa\/","url":"https:\/\/rabsportsnews.com\/tag\/moses-waiswa\/","name":"Moses Waiswa Archives -","isPartOf":{"@id":"https:\/\/rabsportsnews.com\/#website"},"breadcrumb":{"@id":"https:\/\/rabsportsnews.com\/tag\/moses-waiswa\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/rabsportsnews.com\/tag\/moses-waiswa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rabsportsnews.com\/"},{"@type":"ListItem","position":2,"name":"Moses Waiswa"}]},{"@type":"WebSite","@id":"https:\/\/rabsportsnews.com\/#website","url":"https:\/\/rabsportsnews.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rabsportsnews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/rabsportsnews.com\/de\/wp-json\/wp\/v2\/tags\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rabsportsnews.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rabsportsnews.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rabsportsnews.com\/de\/wp-json\/wp\/v2\/posts?tags=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}